{"id":13281,"date":"2023-08-30T03:29:18","date_gmt":"2023-08-30T03:29:18","guid":{"rendered":"https:\/\/www.pattayaholidayhomes.com\/?post_type=property&#038;p=13281"},"modified":"2023-08-30T03:29:18","modified_gmt":"2023-08-30T03:29:18","slug":"%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2","status":"publish","type":"property","link":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/","title":{"rendered":"Pattaya Modern Water Park Condo for Sale in the Maldives Condo 1 bedroom, 1 bathroom, furnished and ready to move in Pattaya Pool view room"},"content":{"rendered":"<body><p>Modern Water Park Condo for Sale in Jomtien Pattaya, Maldives Pattaya Condo or Laguna Beach Resort Condo with complete amenities<\/p>\n<p>1Bedroom 1Bathroom<\/p>\n<p>42 Square Meters<\/p>\n<p>Electrical appliances in their entirety and There is a washing machine available.<\/p>\n<p>View of the swimming pool from the room<\/p>\n<p>Fully furnished and ready for occupancy<\/p>\n<p>Foreign Ownership<\/p>\n<\/body>","protected":false},"excerpt":{"rendered":"<p>\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e04\u0e2d\u0e19\u0e42\u0e14 Maldives Pattaya \u0e2b\u0e23\u0e37\u0e2d \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 42 \u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e21\u0e15\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e04\u0e23\u0e1a \u0e21\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32 \u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e04\u0e23\u0e1a\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48 \u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0b\u0e37\u0e49\u0e2d\u0e44\u0e14\u0e49<\/p>","protected":false},"author":1,"featured_media":13283,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","property-feature":[21,19,119,149,24,125,498,121,144,126,127,141,123,16,38,36,492],"property-type":[118],"property-city":[40],"property-status":[30],"class_list":["post-13281","property","type-property","status-publish","has-post-thumbnail","hentry","property-feature-european-kitchen","property-feature-fridge","property-feature-fire-escape","property-feature-parking-space","property-feature-tv","property-feature-security-guard","property-feature-498","property-feature-communal-pool","property-feature-gym","property-feature-washing-machine","property-feature-water-heater","property-feature-electric-stove","property-feature-fully-furnished","property-feature-air-conditioning","property-feature-sofa","property-feature-close-to-beach","property-feature--close-to-sukhumvit-road","property-type----condo-pattaya","property-city--jomtien-pattaya","property-status-30"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33 Maldives Jomtien Pattaya \u0e2b\u0e23\u0e37\u0e2d \u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e04\u0e23\u0e1a \u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"k4Xsz5vENP_zJZL1pDKFi3kcM9oHD7xabjlUVTa47KQ\" \/>\n\t<meta name=\"msvalidate.01\" content=\"9BA45496AEB85893F60556C3835886FF\" \/>\n\t<meta name=\"yandex-verification\" content=\"2c2a6a83139d83a0\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e02\u0e32\u0e22-\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e43\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 - Pattaya Houses, Pool Villas and Condos for sale and for rent | \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e23\u0e27\u0e21\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e02\u0e32\u0e22-\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e43\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e23\u0e32\u0e04\u0e32\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33\" \/>\n\t\t<meta property=\"og:description\" content=\"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33 Maldives Jomtien Pattaya \u0e2b\u0e23\u0e37\u0e2d \u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e04\u0e23\u0e1a \u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"412\" \/>\n\t\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-08-30T03:29:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-08-30T03:29:18+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/---2314524575242244\/\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/web.facebook.com\/pattayahotproperties\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@IvonkaP3\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33 Maldives Jomtien Pattaya \u0e2b\u0e23\u0e37\u0e2d \u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e04\u0e23\u0e1a \u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@IvonkaP3\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2020\/11\/logo.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/#listItem\",\"name\":\"Properties\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/#listItem\",\"position\":2,\"name\":\"Properties\",\"item\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property-feature\\\/air-conditioning\\\/#listItem\",\"name\":\"\\u0e41\\u0e2d\\u0e23\\u0e4c\\u0e40\\u0e04\\u0e23\\u0e37\\u0e48\\u0e2d\\u0e07\\u0e1b\\u0e23\\u0e31\\u0e1a\\u0e2d\\u0e32\\u0e01\\u0e32\\u0e28\\\/Air Conditioning\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property-feature\\\/air-conditioning\\\/#listItem\",\"position\":3,\"name\":\"\\u0e41\\u0e2d\\u0e23\\u0e4c\\u0e40\\u0e04\\u0e23\\u0e37\\u0e48\\u0e2d\\u0e07\\u0e1b\\u0e23\\u0e31\\u0e1a\\u0e2d\\u0e32\\u0e01\\u0e32\\u0e28\\\/Air Conditioning\",\"item\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property-feature\\\/air-conditioning\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\\\/#listItem\",\"name\":\"\\u0e02\\u0e32\\u0e22\\u0e04\\u0e2d\\u0e19\\u0e42\\u0e14\\u0e21\\u0e31\\u0e25\\u0e14\\u0e35\\u0e1f\\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32 \\u0e04\\u0e2d\\u0e19\\u0e42\\u0e14\\u0e2a\\u0e27\\u0e19\\u0e19\\u0e49\\u0e33\\u0e17\\u0e31\\u0e19\\u0e2a\\u0e21\\u0e31\\u0e22\\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32 \\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e27\\u0e34\\u0e27\\u0e2a\\u0e23\\u0e30\\u0e27\\u0e48\\u0e32\\u0e22\\u0e19\\u0e49\\u0e33 1\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e19\\u0e2d\\u0e19 1\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e19\\u0e49\\u0e33 \\u0e15\\u0e01\\u0e41\\u0e15\\u0e48\\u0e07\\u0e1e\\u0e23\\u0e49\\u0e2d\\u0e21\\u0e40\\u0e02\\u0e49\\u0e32\\u0e2d\\u0e22\\u0e39\\u0e48\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/#listItem\",\"name\":\"Properties\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\\\/#listItem\",\"position\":4,\"name\":\"\\u0e02\\u0e32\\u0e22\\u0e04\\u0e2d\\u0e19\\u0e42\\u0e14\\u0e21\\u0e31\\u0e25\\u0e14\\u0e35\\u0e1f\\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32 \\u0e04\\u0e2d\\u0e19\\u0e42\\u0e14\\u0e2a\\u0e27\\u0e19\\u0e19\\u0e49\\u0e33\\u0e17\\u0e31\\u0e19\\u0e2a\\u0e21\\u0e31\\u0e22\\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32 \\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e27\\u0e34\\u0e27\\u0e2a\\u0e23\\u0e30\\u0e27\\u0e48\\u0e32\\u0e22\\u0e19\\u0e49\\u0e33 1\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e19\\u0e2d\\u0e19 1\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e19\\u0e49\\u0e33 \\u0e15\\u0e01\\u0e41\\u0e15\\u0e48\\u0e07\\u0e1e\\u0e23\\u0e49\\u0e2d\\u0e21\\u0e40\\u0e02\\u0e49\\u0e32\\u0e2d\\u0e22\\u0e39\\u0e48\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property-feature\\\/air-conditioning\\\/#listItem\",\"name\":\"\\u0e41\\u0e2d\\u0e23\\u0e4c\\u0e40\\u0e04\\u0e23\\u0e37\\u0e48\\u0e2d\\u0e07\\u0e1b\\u0e23\\u0e31\\u0e1a\\u0e2d\\u0e32\\u0e01\\u0e32\\u0e28\\\/Air Conditioning\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/#organization\",\"name\":\"pattayaholidayhomes\",\"description\":\"\\u0e41\\u0e2b\\u0e25\\u0e48\\u0e07\\u0e23\\u0e27\\u0e21\\u0e1a\\u0e49\\u0e32\\u0e19 \\u0e04\\u0e2d\\u0e19\\u0e42\\u0e14 \\u0e17\\u0e35\\u0e48\\u0e14\\u0e34\\u0e19 \\u0e2d\\u0e2a\\u0e31\\u0e07\\u0e2b\\u0e32\\u0e23\\u0e34\\u0e21\\u0e17\\u0e23\\u0e31\\u0e1e\\u0e22\\u0e4c \\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32 \\u0e02\\u0e32\\u0e22-\\u0e43\\u0e2b\\u0e49\\u0e40\\u0e0a\\u0e48\\u0e32\\u0e43\\u0e19\\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32\\u0e23\\u0e32\\u0e04\\u0e32\\u0e14\\u0e35\\u0e17\\u0e35\\u0e48\\u0e2a\\u0e38\\u0e14\",\"url\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/\",\"telephone\":\"+66863374525\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/logo.jpg\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\\\/#organizationLogo\",\"width\":112,\"height\":108,\"caption\":\"Pattaya Real Estate Agent\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/---2314524575242244\\\/\",\"https:\\\/\\\/x.com\\\/IvonkaP3\",\"https:\\\/\\\/www.youtube.com\\\/@pattayaholidayhomes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/\\u0e0b\\u0e37\\u0e2d-\\u0e02\\u0e32\\u0e22-\\u0e40\\u0e0a\\u0e48\\u0e32-\\u0e1a\\u0e49\\u0e32\\u0e19-\\u0e04\\u0e2d\\u0e19\\u0e42\\u0e14-\\u0e17\\u0e35\\u0e48\\u0e14\\u0e34\\u0e19-\\u0e2d\\u0e2a\\u0e31\\u0e07\\u0e2b\\u0e32\\u0e23\\u0e34\\u0e21\\u0e17\\u0e23\\u0e31\\u0e1e\\u0e22\\u0e4c\\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32.jpg\",\"width\":313,\"height\":302},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/pattayahotproperties\",\"https:\\\/\\\/x.com\\\/IvonkaP3\",\"https:\\\/\\\/www.youtube.com\\\/@pattayaholidayhomes\"],\"knowsLanguage\":[\"thai\",\"english\"]},{\"@type\":\"RealEstateListing\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\\\/#realestatelisting\",\"url\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\\\/\",\"name\":\"\\u0e02\\u0e32\\u0e22\\u0e04\\u0e2d\\u0e19\\u0e42\\u0e14\\u0e21\\u0e31\\u0e25\\u0e14\\u0e35\\u0e1f\\u0e08\\u0e2d\\u0e21\\u0e40\\u0e17\\u0e35\\u0e22\\u0e19\\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32 \\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e27\\u0e34\\u0e27\\u0e2a\\u0e23\\u0e30\\u0e27\\u0e48\\u0e32\\u0e22\\u0e19\\u0e49\\u0e33 1\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e19\\u0e2d\\u0e19 1\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e19\\u0e49\\u0e33\",\"description\":\"\\u0e02\\u0e32\\u0e22\\u0e04\\u0e2d\\u0e19\\u0e42\\u0e14\\u0e2a\\u0e27\\u0e19\\u0e19\\u0e49\\u0e33 Maldives Jomtien Pattaya \\u0e2b\\u0e23\\u0e37\\u0e2d \\u0e25\\u0e32\\u0e01\\u0e39\\u0e19\\u0e48\\u0e32\\u0e1a\\u0e35\\u0e0a\\u0e23\\u0e35\\u0e2a\\u0e2d\\u0e23\\u0e4c\\u0e17 \\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e27\\u0e34\\u0e27\\u0e2a\\u0e23\\u0e30\\u0e27\\u0e48\\u0e32\\u0e22\\u0e19\\u0e49\\u0e33 1\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e19\\u0e2d\\u0e19 1\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e19\\u0e49\\u0e33 \\u0e40\\u0e1f\\u0e2d\\u0e23\\u0e4c\\u0e19\\u0e34\\u0e40\\u0e08\\u0e2d\\u0e23\\u0e4c\\u0e04\\u0e23\\u0e1a \\u0e2a\\u0e34\\u0e48\\u0e07\\u0e2d\\u0e33\\u0e19\\u0e27\\u0e22\\u0e04\\u0e27\\u0e32\\u0e21\\u0e2a\\u0e30\\u0e14\\u0e27\\u0e01 \\u0e2a\\u0e27\\u0e19\\u0e19\\u0e49\\u0e33\\u0e02\\u0e19\\u0e32\\u0e14\\u0e43\\u0e2b\\u0e0d\\u0e48\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/\\u0e02\\u0e32\\u0e22\\u0e04\\u0e2d\\u0e19\\u0e42\\u0e14\\u0e25\\u0e32\\u0e01\\u0e39\\u0e19\\u0e48\\u0e32\\u0e1a\\u0e35\\u0e0a\\u0e23\\u0e35\\u0e2a\\u0e2d\\u0e23\\u0e4c\\u0e173-\\u0e21\\u0e31\\u0e25\\u0e14\\u0e35\\u0e1f\\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32-\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e27\\u0e34\\u0e27\\u0e2a\\u0e23\\u0e30\\u0e27\\u0e48\\u0e32\\u0e22\\u0e19\\u0e49\\u0e33.jpg\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\\\/#mainImage\",\"width\":412,\"height\":267,\"caption\":\"\\u0e02\\u0e32\\u0e22\\u0e04\\u0e2d\\u0e19\\u0e42\\u0e14\\u0e21\\u0e31\\u0e25\\u0e14\\u0e35\\u0e1f\\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32 \\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e27\\u0e34\\u0e27\\u0e2a\\u0e23\\u0e30 1\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e19\\u0e2d\\u0e19 1\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e19\\u0e49\\u0e33\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\\\/#mainImage\"},\"datePublished\":\"2023-08-30T03:29:18+00:00\",\"dateModified\":\"2023-08-30T03:29:18+00:00\",\"datePosted\":\"2023-08-30T03:29:18+00:00\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\\\/#webpage\",\"url\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\\\/\",\"name\":\"\\u0e02\\u0e32\\u0e22\\u0e04\\u0e2d\\u0e19\\u0e42\\u0e14\\u0e21\\u0e31\\u0e25\\u0e14\\u0e35\\u0e1f\\u0e08\\u0e2d\\u0e21\\u0e40\\u0e17\\u0e35\\u0e22\\u0e19\\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32 \\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e27\\u0e34\\u0e27\\u0e2a\\u0e23\\u0e30\\u0e27\\u0e48\\u0e32\\u0e22\\u0e19\\u0e49\\u0e33 1\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e19\\u0e2d\\u0e19 1\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e19\\u0e49\\u0e33\",\"description\":\"\\u0e02\\u0e32\\u0e22\\u0e04\\u0e2d\\u0e19\\u0e42\\u0e14\\u0e2a\\u0e27\\u0e19\\u0e19\\u0e49\\u0e33 Maldives Jomtien Pattaya \\u0e2b\\u0e23\\u0e37\\u0e2d \\u0e25\\u0e32\\u0e01\\u0e39\\u0e19\\u0e48\\u0e32\\u0e1a\\u0e35\\u0e0a\\u0e23\\u0e35\\u0e2a\\u0e2d\\u0e23\\u0e4c\\u0e17 \\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e27\\u0e34\\u0e27\\u0e2a\\u0e23\\u0e30\\u0e27\\u0e48\\u0e32\\u0e22\\u0e19\\u0e49\\u0e33 1\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e19\\u0e2d\\u0e19 1\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e19\\u0e49\\u0e33 \\u0e40\\u0e1f\\u0e2d\\u0e23\\u0e4c\\u0e19\\u0e34\\u0e40\\u0e08\\u0e2d\\u0e23\\u0e4c\\u0e04\\u0e23\\u0e1a \\u0e2a\\u0e34\\u0e48\\u0e07\\u0e2d\\u0e33\\u0e19\\u0e27\\u0e22\\u0e04\\u0e27\\u0e32\\u0e21\\u0e2a\\u0e30\\u0e14\\u0e27\\u0e01 \\u0e2a\\u0e27\\u0e19\\u0e19\\u0e49\\u0e33\\u0e02\\u0e19\\u0e32\\u0e14\\u0e43\\u0e2b\\u0e0d\\u0e48\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/\\u0e02\\u0e32\\u0e22\\u0e04\\u0e2d\\u0e19\\u0e42\\u0e14\\u0e25\\u0e32\\u0e01\\u0e39\\u0e19\\u0e48\\u0e32\\u0e1a\\u0e35\\u0e0a\\u0e23\\u0e35\\u0e2a\\u0e2d\\u0e23\\u0e4c\\u0e173-\\u0e21\\u0e31\\u0e25\\u0e14\\u0e35\\u0e1f\\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32-\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e27\\u0e34\\u0e27\\u0e2a\\u0e23\\u0e30\\u0e27\\u0e48\\u0e32\\u0e22\\u0e19\\u0e49\\u0e33.jpg\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\\\/#mainImage\",\"width\":412,\"height\":267,\"caption\":\"\\u0e02\\u0e32\\u0e22\\u0e04\\u0e2d\\u0e19\\u0e42\\u0e14\\u0e21\\u0e31\\u0e25\\u0e14\\u0e35\\u0e1f\\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32 \\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e27\\u0e34\\u0e27\\u0e2a\\u0e23\\u0e30 1\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e19\\u0e2d\\u0e19 1\\u0e2b\\u0e49\\u0e2d\\u0e07\\u0e19\\u0e49\\u0e33\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/property\\\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\\\/#mainImage\"},\"datePublished\":\"2023-08-30T03:29:18+00:00\",\"dateModified\":\"2023-08-30T03:29:18+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/\",\"name\":\"\\u0e1a\\u0e49\\u0e32\\u0e19\\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32 \\u0e04\\u0e2d\\u0e19\\u0e42\\u0e14\\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32 \\u0e17\\u0e35\\u0e48\\u0e14\\u0e34\\u0e19\\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32 \\u0e02\\u0e32\\u0e22-\\u0e43\\u0e2b\\u0e49\\u0e40\\u0e0a\\u0e48\\u0e32 \\u0e2d\\u0e2a\\u0e31\\u0e07\\u0e2b\\u0e32\\u0e23\\u0e34\\u0e21\\u0e17\\u0e23\\u0e31\\u0e1e\\u0e22\\u0e4c\\u0e43\\u0e19\\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32 - Pattaya Houses, Pool Villas and Condos for sale and for rent\",\"description\":\"\\u0e41\\u0e2b\\u0e25\\u0e48\\u0e07\\u0e23\\u0e27\\u0e21\\u0e1a\\u0e49\\u0e32\\u0e19 \\u0e04\\u0e2d\\u0e19\\u0e42\\u0e14 \\u0e17\\u0e35\\u0e48\\u0e14\\u0e34\\u0e19 \\u0e2d\\u0e2a\\u0e31\\u0e07\\u0e2b\\u0e32\\u0e23\\u0e34\\u0e21\\u0e17\\u0e23\\u0e31\\u0e1e\\u0e22\\u0e4c \\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32 \\u0e02\\u0e32\\u0e22-\\u0e43\\u0e2b\\u0e49\\u0e40\\u0e0a\\u0e48\\u0e32\\u0e43\\u0e19\\u0e1e\\u0e31\\u0e17\\u0e22\\u0e32\\u0e23\\u0e32\\u0e04\\u0e32\\u0e14\\u0e35\\u0e17\\u0e35\\u0e48\\u0e2a\\u0e38\\u0e14\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pattayaholidayhomes.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33<\/title>\n\n","aioseo_head_json":{"title":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","description":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33 Maldives Jomtien Pattaya \u0e2b\u0e23\u0e37\u0e2d \u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e04\u0e23\u0e1a \u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48","canonical_url":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"k4Xsz5vENP_zJZL1pDKFi3kcM9oHD7xabjlUVTa47KQ","msvalidate.01":"9BA45496AEB85893F60556C3835886FF","yandex-verification":"2c2a6a83139d83a0","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.pattayaholidayhomes.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/www.pattayaholidayhomes.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/#listItem","name":"Properties"}},{"@type":"ListItem","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/#listItem","position":2,"name":"Properties","item":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property-feature\/air-conditioning\/#listItem","name":"\u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\/Air Conditioning"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.pattayaholidayhomes.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property-feature\/air-conditioning\/#listItem","position":3,"name":"\u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\/Air Conditioning","item":"https:\/\/www.pattayaholidayhomes.com\/en\/property-feature\/air-conditioning\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/#listItem","name":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/#listItem","name":"Properties"}},{"@type":"ListItem","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/#listItem","position":4,"name":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48","previousItem":{"@type":"ListItem","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property-feature\/air-conditioning\/#listItem","name":"\u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\/Air Conditioning"}}]},{"@type":"Organization","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/#organization","name":"pattayaholidayhomes","description":"\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e23\u0e27\u0e21\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e02\u0e32\u0e22-\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e43\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e23\u0e32\u0e04\u0e32\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14","url":"https:\/\/www.pattayaholidayhomes.com\/en\/","telephone":"+66863374525","logo":{"@type":"ImageObject","url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2020\/11\/logo.jpg","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/#organizationLogo","width":112,"height":108,"caption":"Pattaya Real Estate Agent"},"image":{"@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/---2314524575242244\/","https:\/\/x.com\/IvonkaP3","https:\/\/www.youtube.com\/@pattayaholidayhomes"]},{"@type":"Person","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/author\/admin\/#author","url":"https:\/\/www.pattayaholidayhomes.com\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/#authorImage","url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2026\/04\/\u0e0b\u0e37\u0e2d-\u0e02\u0e32\u0e22-\u0e40\u0e0a\u0e48\u0e32-\u0e1a\u0e49\u0e32\u0e19-\u0e04\u0e2d\u0e19\u0e42\u0e14-\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19-\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1e\u0e31\u0e17\u0e22\u0e32.jpg","width":313,"height":302},"sameAs":["https:\/\/web.facebook.com\/pattayahotproperties","https:\/\/x.com\/IvonkaP3","https:\/\/www.youtube.com\/@pattayaholidayhomes"],"knowsLanguage":["thai","english"]},{"@type":"RealEstateListing","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/#realestatelisting","url":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/","name":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","description":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33 Maldives Jomtien Pattaya \u0e2b\u0e23\u0e37\u0e2d \u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e04\u0e23\u0e1a \u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.pattayaholidayhomes.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/#breadcrumblist"},"author":{"@id":"https:\/\/www.pattayaholidayhomes.com\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.pattayaholidayhomes.com\/en\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33.jpg","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/#mainImage","width":412,"height":267,"caption":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33"},"primaryImageOfPage":{"@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/#mainImage"},"datePublished":"2023-08-30T03:29:18+00:00","dateModified":"2023-08-30T03:29:18+00:00","datePosted":"2023-08-30T03:29:18+00:00"},{"@type":"WebPage","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/#webpage","url":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/","name":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","description":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33 Maldives Jomtien Pattaya \u0e2b\u0e23\u0e37\u0e2d \u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e04\u0e23\u0e1a \u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.pattayaholidayhomes.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/#breadcrumblist"},"author":{"@id":"https:\/\/www.pattayaholidayhomes.com\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.pattayaholidayhomes.com\/en\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33.jpg","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/#mainImage","width":412,"height":267,"caption":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33"},"primaryImageOfPage":{"@id":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/#mainImage"},"datePublished":"2023-08-30T03:29:18+00:00","dateModified":"2023-08-30T03:29:18+00:00"},{"@type":"WebSite","@id":"https:\/\/www.pattayaholidayhomes.com\/en\/#website","url":"https:\/\/www.pattayaholidayhomes.com\/en\/","name":"\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e02\u0e32\u0e22-\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e43\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 - Pattaya Houses, Pool Villas and Condos for sale and for rent","description":"\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e23\u0e27\u0e21\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e02\u0e32\u0e22-\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e43\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e23\u0e32\u0e04\u0e32\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.pattayaholidayhomes.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e02\u0e32\u0e22-\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e43\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 - Pattaya Houses, Pool Villas and Condos for sale and for rent | \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e23\u0e27\u0e21\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e02\u0e32\u0e22-\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e43\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e23\u0e32\u0e04\u0e32\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14","og:type":"article","og:title":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","og:description":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33 Maldives Jomtien Pattaya \u0e2b\u0e23\u0e37\u0e2d \u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e04\u0e23\u0e1a \u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48","og:url":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/","og:image":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33.jpg","og:image:secure_url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33.jpg","og:image:width":412,"og:image:height":267,"article:published_time":"2023-08-30T03:29:18+00:00","article:modified_time":"2023-08-30T03:29:18+00:00","article:publisher":"https:\/\/www.facebook.com\/---2314524575242244\/","article:author":"https:\/\/web.facebook.com\/pattayahotproperties","twitter:card":"summary","twitter:site":"@IvonkaP3","twitter:title":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","twitter:description":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33 Maldives Jomtien Pattaya \u0e2b\u0e23\u0e37\u0e2d \u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e04\u0e23\u0e1a \u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48","twitter:creator":"@IvonkaP3","twitter:image":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2020\/11\/logo.jpg","twitter:label1":"Written by","twitter:data1":"admin"},"aioseo_meta_data":{"post_id":"13281","title":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","description":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33 Maldives Jomtien Pattaya \u0e2b\u0e23\u0e37\u0e2d \u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e04\u0e23\u0e1a \u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48","keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-05-13 00:55:46","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2023-08-30 02:13:30","updated":"2026-05-13 00:55:46","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.pattayaholidayhomes.com\/en\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.pattayaholidayhomes.com\/en\/property\/\" title=\"Properties\">Properties<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.pattayaholidayhomes.com\/en\/property-feature\/air-conditioning\/\" title=\"\u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\/Air Conditioning\">\u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\/Air Conditioning<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/\" title=\"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\">\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48<\/a>\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.pattayaholidayhomes.com\/en"},{"label":"Properties","link":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/"},{"label":"\u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\/Air Conditioning","link":"https:\/\/www.pattayaholidayhomes.com\/en\/property-feature\/air-conditioning\/"},{"label":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48","link":"https:\/\/www.pattayaholidayhomes.com\/en\/property\/%e0%b8%82%e0%b8%b2%e0%b8%a2%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b9%82%e0%b8%94%e0%b8%a1%e0%b8%b1%e0%b8%a5%e0%b8%94%e0%b8%b5%e0%b8%9f%e0%b8%9e%e0%b8%b1%e0%b8%97%e0%b8%a2%e0%b8%b2\/"}],"property_meta":{"REAL_HOMES_property_price":"1900000","REAL_HOMES_property_old_price":"","REAL_HOMES_property_price_prefix":"","REAL_HOMES_property_price_postfix":"","REAL_HOMES_property_size":"42","REAL_HOMES_property_size_postfix":"\u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e21\u0e15\u0e23\/Square Meters","REAL_HOMES_property_lot_size":"","REAL_HOMES_property_lot_size_postfix":"","REAL_HOMES_property_bedrooms":"1","REAL_HOMES_property_bathrooms":"1","REAL_HOMES_property_garage":"","REAL_HOMES_property_id":"RH-13281-property","REAL_HOMES_property_year_built":"","rvr_property_owner":"","REAL_HOMES_featured":"0","REAL_HOMES_additional_details_list":[],"REAL_HOMES_property_location":{"latitude":"12.8958204","longitude":"100.8833457","zoom":"14"},"REAL_HOMES_property_address":"VVWM+88H, Pattaya City, Bang Lamung District, Chon Buri 20150, Thailand","REAL_HOMES_property_map":"0","REAL_HOMES_property_images":[{"width":150,"height":150,"file":"2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33.jpg","filesize":30311,"sizes":{"medium":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33-300x194.jpg","width":300,"height":194,"mime-type":"image\/jpeg","filesize":21182,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33-300x194.jpg"},"thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":9618,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33-150x150.jpg"},"post-thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33-150x97.jpg","width":150,"height":97,"mime-type":"image\/jpeg","filesize":7240,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33-150x97.jpg"},"agent-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":15960,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33-210x210.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"13283","name":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33.jpg","path":"\/var\/www\/vhosts\/pattayaholidayhomes.com\/httpdocs\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33.jpg","url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33-150x150.jpg","full_url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33.jpg","title":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173 \u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33","caption":"","description":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","alt":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","srcset":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33-150x150.jpg 150w, https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33-210x210.jpg 210w"},{"width":150,"height":150,"file":"2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331.jpg","filesize":57560,"sizes":{"medium":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331-225x300.jpg","width":225,"height":300,"mime-type":"image\/jpeg","filesize":22504,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331-225x300.jpg"},"thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":9312,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331-150x150.jpg"},"post-thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331-112x150.jpg","width":112,"height":150,"mime-type":"image\/jpeg","filesize":6850,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331-112x150.jpg"},"modern-property-child-slider":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331-412x510.jpg","width":412,"height":510,"mime-type":"image\/jpeg","filesize":67239,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331-412x510.jpg"},"property-thumb-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331-412x326.jpg","width":412,"height":326,"mime-type":"image\/jpeg","filesize":44632,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331-412x326.jpg"},"property-detail-video-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331-412x417.jpg","width":412,"height":417,"mime-type":"image\/jpeg","filesize":58200,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331-412x417.jpg"},"agent-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":16674,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331-210x210.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"13284","name":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331.jpg","path":"\/var\/www\/vhosts\/pattayaholidayhomes.com\/httpdocs\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331.jpg","url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331-150x150.jpg","full_url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331.jpg","title":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173 \u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331","caption":"","description":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","alt":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","srcset":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331-150x150.jpg 150w, https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e331-210x210.jpg 210w"},{"width":150,"height":150,"file":"2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332.jpg","filesize":43409,"sizes":{"medium":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332-225x300.jpg","width":225,"height":300,"mime-type":"image\/jpeg","filesize":18256,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332-225x300.jpg"},"thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":8088,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332-150x150.jpg"},"post-thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332-112x150.jpg","width":112,"height":150,"mime-type":"image\/jpeg","filesize":5829,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332-112x150.jpg"},"modern-property-child-slider":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332-412x510.jpg","width":412,"height":510,"mime-type":"image\/jpeg","filesize":52420,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332-412x510.jpg"},"property-thumb-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332-412x326.jpg","width":412,"height":326,"mime-type":"image\/jpeg","filesize":37538,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332-412x326.jpg"},"property-detail-video-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332-412x417.jpg","width":412,"height":417,"mime-type":"image\/jpeg","filesize":46917,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332-412x417.jpg"},"agent-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":14148,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332-210x210.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"13285","name":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332.jpg","path":"\/var\/www\/vhosts\/pattayaholidayhomes.com\/httpdocs\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332.jpg","url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332-150x150.jpg","full_url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332.jpg","title":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173 \u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332","caption":"","description":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","alt":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","srcset":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332-150x150.jpg 150w, https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e332-210x210.jpg 210w"},{"width":150,"height":150,"file":"2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333.jpg","filesize":27141,"sizes":{"medium":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333-225x300.jpg","width":225,"height":300,"mime-type":"image\/jpeg","filesize":12392,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333-225x300.jpg"},"thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5820,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333-150x150.jpg"},"post-thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333-112x150.jpg","width":112,"height":150,"mime-type":"image\/jpeg","filesize":4507,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333-112x150.jpg"},"modern-property-child-slider":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333-412x510.jpg","width":412,"height":510,"mime-type":"image\/jpeg","filesize":32161,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333-412x510.jpg"},"property-thumb-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333-412x326.jpg","width":412,"height":326,"mime-type":"image\/jpeg","filesize":21827,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333-412x326.jpg"},"property-detail-video-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333-412x417.jpg","width":412,"height":417,"mime-type":"image\/jpeg","filesize":28191,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333-412x417.jpg"},"agent-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":9412,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333-210x210.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"13286","name":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333.jpg","path":"\/var\/www\/vhosts\/pattayaholidayhomes.com\/httpdocs\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333.jpg","url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333-150x150.jpg","full_url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333.jpg","title":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173 \u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333","caption":"","description":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","alt":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","srcset":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333-150x150.jpg 150w, https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e333-210x210.jpg 210w"},{"width":150,"height":150,"file":"2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e334.jpg","filesize":19779,"sizes":{"medium":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e334-300x225.jpg","width":300,"height":225,"mime-type":"image\/jpeg","filesize":14070,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e334-300x225.jpg"},"thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e334-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6203,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e334-150x150.jpg"},"post-thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e334-150x113.jpg","width":150,"height":113,"mime-type":"image\/jpeg","filesize":5286,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e334-150x113.jpg"},"agent-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e334-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":9940,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e334-210x210.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"13287","name":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e334.jpg","path":"\/var\/www\/vhosts\/pattayaholidayhomes.com\/httpdocs\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e334.jpg","url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e334-150x150.jpg","full_url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e334.jpg","title":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173 \u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e334","caption":"","description":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","alt":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","srcset":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e334-150x150.jpg 150w, https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e334-210x210.jpg 210w"},{"width":150,"height":150,"file":"2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e335.jpg","filesize":22892,"sizes":{"medium":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e335-300x225.jpg","width":300,"height":225,"mime-type":"image\/jpeg","filesize":15776,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e335-300x225.jpg"},"thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e335-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6496,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e335-150x150.jpg"},"post-thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e335-150x113.jpg","width":150,"height":113,"mime-type":"image\/jpeg","filesize":5673,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e335-150x113.jpg"},"agent-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e335-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":10764,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e335-210x210.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"13288","name":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e335.jpg","path":"\/var\/www\/vhosts\/pattayaholidayhomes.com\/httpdocs\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e335.jpg","url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e335-150x150.jpg","full_url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e335.jpg","title":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173 \u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e335","caption":"","description":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","alt":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","srcset":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e335-150x150.jpg 150w, https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e335-210x210.jpg 210w"},{"width":150,"height":150,"file":"2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336.jpg","filesize":22437,"sizes":{"medium":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336-225x300.jpg","width":225,"height":300,"mime-type":"image\/jpeg","filesize":10914,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336-225x300.jpg"},"thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":4887,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336-150x150.jpg"},"post-thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336-112x150.jpg","width":112,"height":150,"mime-type":"image\/jpeg","filesize":4054,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336-112x150.jpg"},"modern-property-child-slider":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336-412x510.jpg","width":412,"height":510,"mime-type":"image\/jpeg","filesize":26823,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336-412x510.jpg"},"property-thumb-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336-412x326.jpg","width":412,"height":326,"mime-type":"image\/jpeg","filesize":15972,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336-412x326.jpg"},"property-detail-video-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336-412x417.jpg","width":412,"height":417,"mime-type":"image\/jpeg","filesize":22283,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336-412x417.jpg"},"agent-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":7849,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336-210x210.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"13289","name":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336.jpg","path":"\/var\/www\/vhosts\/pattayaholidayhomes.com\/httpdocs\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336.jpg","url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336-150x150.jpg","full_url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336.jpg","title":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173 \u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336","caption":"","description":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","alt":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","srcset":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336-150x150.jpg 150w, https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e336-210x210.jpg 210w"},{"width":150,"height":150,"file":"2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337.jpg","filesize":12413,"sizes":{"medium":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337-225x300.jpg","width":225,"height":300,"mime-type":"image\/jpeg","filesize":6718,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337-225x300.jpg"},"thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":3161,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337-150x150.jpg"},"post-thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337-112x150.jpg","width":112,"height":150,"mime-type":"image\/jpeg","filesize":2754,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337-112x150.jpg"},"modern-property-child-slider":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337-412x510.jpg","width":412,"height":510,"mime-type":"image\/jpeg","filesize":15742,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337-412x510.jpg"},"property-thumb-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337-412x326.jpg","width":412,"height":326,"mime-type":"image\/jpeg","filesize":8978,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337-412x326.jpg"},"property-detail-video-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337-412x417.jpg","width":412,"height":417,"mime-type":"image\/jpeg","filesize":12810,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337-412x417.jpg"},"agent-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":4915,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337-210x210.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"13290","name":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337.jpg","path":"\/var\/www\/vhosts\/pattayaholidayhomes.com\/httpdocs\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337.jpg","url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337-150x150.jpg","full_url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337.jpg","title":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173 \u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337","caption":"","description":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","alt":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","srcset":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337-150x150.jpg 150w, https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e337-210x210.jpg 210w"},{"width":150,"height":150,"file":"2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e338.jpg","filesize":12489,"sizes":{"medium":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e338-300x225.jpg","width":300,"height":225,"mime-type":"image\/jpeg","filesize":9651,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e338-300x225.jpg"},"thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e338-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":4936,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e338-150x150.jpg"},"post-thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e338-150x113.jpg","width":150,"height":113,"mime-type":"image\/jpeg","filesize":4137,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e338-150x113.jpg"},"agent-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e338-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":7438,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e338-210x210.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"13291","name":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e338.jpg","path":"\/var\/www\/vhosts\/pattayaholidayhomes.com\/httpdocs\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e338.jpg","url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e338-150x150.jpg","full_url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e338.jpg","title":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173 \u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e338","caption":"","description":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","alt":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","srcset":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e338-150x150.jpg 150w, https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e338-210x210.jpg 210w"},{"width":150,"height":150,"file":"2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339.jpg","filesize":18118,"sizes":{"medium":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339-225x300.jpg","width":225,"height":300,"mime-type":"image\/jpeg","filesize":9050,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339-225x300.jpg"},"thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":4201,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339-150x150.jpg"},"post-thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339-112x150.jpg","width":112,"height":150,"mime-type":"image\/jpeg","filesize":3582,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339-112x150.jpg"},"modern-property-child-slider":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339-412x510.jpg","width":412,"height":510,"mime-type":"image\/jpeg","filesize":21833,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339-412x510.jpg"},"property-thumb-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339-412x326.jpg","width":412,"height":326,"mime-type":"image\/jpeg","filesize":11722,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339-412x326.jpg"},"property-detail-video-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339-412x417.jpg","width":412,"height":417,"mime-type":"image\/jpeg","filesize":17624,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339-412x417.jpg"},"agent-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":6581,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339-210x210.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"13292","name":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339.jpg","path":"\/var\/www\/vhosts\/pattayaholidayhomes.com\/httpdocs\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339.jpg","url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339-150x150.jpg","full_url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339.jpg","title":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173 \u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339","caption":"","description":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","alt":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","srcset":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339-150x150.jpg 150w, https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e339-210x210.jpg 210w"},{"width":150,"height":150,"file":"2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310.jpg","filesize":25261,"sizes":{"medium":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310-225x300.jpg","width":225,"height":300,"mime-type":"image\/jpeg","filesize":11795,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310-225x300.jpg"},"thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5193,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310-150x150.jpg"},"post-thumbnail":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310-112x150.jpg","width":112,"height":150,"mime-type":"image\/jpeg","filesize":4267,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310-112x150.jpg"},"modern-property-child-slider":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310-412x510.jpg","width":412,"height":510,"mime-type":"image\/jpeg","filesize":29995,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310-412x510.jpg"},"property-thumb-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310-412x326.jpg","width":412,"height":326,"mime-type":"image\/jpeg","filesize":17477,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310-412x326.jpg"},"property-detail-video-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310-412x417.jpg","width":412,"height":417,"mime-type":"image\/jpeg","filesize":24769,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310-412x417.jpg"},"agent-image":{"file":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":8586,"url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310-210x210.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"13293","name":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310.jpg","path":"\/var\/www\/vhosts\/pattayaholidayhomes.com\/httpdocs\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310.jpg","url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310-150x150.jpg","full_url":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310.jpg","title":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173 \u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310","caption":"","description":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","alt":"\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 1\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33","srcset":"https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310-150x150.jpg 150w, https:\/\/www.pattayaholidayhomes.com\/wp-content\/uploads\/2023\/08\/\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e25\u0e32\u0e01\u0e39\u0e19\u0e48\u0e32\u0e1a\u0e35\u0e0a\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e173-\u0e21\u0e31\u0e25\u0e14\u0e35\u0e1f\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e2b\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e3310-210x210.jpg 210w"}],"REAL_HOMES_change_gallery_slider_type":"0","REAL_HOMES_gallery_slider_type":"thumb-on-right","inspiry_floor_plans":[],"inspiry_video_group":[],"REAL_HOMES_360_virtual_tour":"","REAL_HOMES_agent_display_option":"agent_info","REAL_HOMES_agents":["4985"],"REAL_HOMES_display_agency_info":"","REAL_HOMES_property_agency":"","REAL_HOMES_energy_class":"none","REAL_HOMES_energy_performance":"","REAL_HOMES_epc_current_rating":"","REAL_HOMES_epc_potential_rating":"","ere_property_schedule_tour":"global","ere_property_schedule_time_slots":"","ere_property_schedule_description":"","REAL_HOMES_sticky":"0","inspiry_property_label":"","inspiry_property_label_color":"","inspiry_property_tax":"0","inspiry_additional_fee":"0","REAL_HOMES_attachments":[],"inspiry_property_owner_name":"","inspiry_property_owner_contact":"","inspiry_property_owner_address":"","REAL_HOMES_property_private_note":"Sandy Kingland","inspiry_message_to_reviewer":"","REAL_HOMES_add_in_slider":"no","REAL_HOMES_slider_image":[],"REAL_HOMES_page_banner_image":[],"REAL_HOMES_hide_property_advance_search":"0","REAL_HOMES_custom_header_display":"default","REAL_HOMES_custom_header_position":"relative","REAL_HOMES_custom_footer_display":"default","REAL_HOMES_hide_advance_search":"0","REAL_HOMES_custom_search_form":"default","REAL_HOMES_search_form_margin_top":"","REAL_HOMES_search_form_margin_bottom":""},"_links":{"self":[{"href":"https:\/\/www.pattayaholidayhomes.com\/en\/wp-json\/wp\/v2\/property\/13281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pattayaholidayhomes.com\/en\/wp-json\/wp\/v2\/property"}],"about":[{"href":"https:\/\/www.pattayaholidayhomes.com\/en\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/www.pattayaholidayhomes.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pattayaholidayhomes.com\/en\/wp-json\/wp\/v2\/comments?post=13281"}],"version-history":[{"count":0,"href":"https:\/\/www.pattayaholidayhomes.com\/en\/wp-json\/wp\/v2\/property\/13281\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pattayaholidayhomes.com\/en\/wp-json\/wp\/v2\/media\/13283"}],"wp:attachment":[{"href":"https:\/\/www.pattayaholidayhomes.com\/en\/wp-json\/wp\/v2\/media?parent=13281"}],"wp:term":[{"taxonomy":"property-feature","embeddable":true,"href":"https:\/\/www.pattayaholidayhomes.com\/en\/wp-json\/wp\/v2\/property-feature?post=13281"},{"taxonomy":"property-type","embeddable":true,"href":"https:\/\/www.pattayaholidayhomes.com\/en\/wp-json\/wp\/v2\/property-type?post=13281"},{"taxonomy":"property-city","embeddable":true,"href":"https:\/\/www.pattayaholidayhomes.com\/en\/wp-json\/wp\/v2\/property-city?post=13281"},{"taxonomy":"property-status","embeddable":true,"href":"https:\/\/www.pattayaholidayhomes.com\/en\/wp-json\/wp\/v2\/property-status?post=13281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}